{"id":2139,"date":"2015-04-28T21:10:37","date_gmt":"2015-04-28T21:10:37","guid":{"rendered":"http:\/\/www.misdetallesdeboda.com\/detalles\/?post_type=product&#038;p=2139"},"modified":"2024-11-29T10:56:52","modified_gmt":"2024-11-29T10:56:52","slug":"bolsa-de-yute-y-tela-13x9cm","status":"publish","type":"product","link":"https:\/\/www.misdetallesdeboda.com\/detalles\/producto\/bolsa-de-yute-y-tela-13x9cm\/","title":{"rendered":"Bolsa de yute y tela con tarjeta personalizada"},"content":{"rendered":"<p>Preciosa bolsa para meter los detalles de la boda, bautizo o comuni\u00f3n.<\/p>\n<p>Esta bolsita combina los materiales de jute y tela color blanco roto.<\/p>\n<p>Decorada con lazo de yute con bot\u00f3n de madera en el centro del lazo.<\/p>\n<p>Medidas: 13.5cm (altura) x 9.7cm (anchura)<\/p>\n<p>Pedido m\u00ednimo 20 unidades.<br \/>\nOFERTA: GRATIS TARJETA RECORDATORIA DE CARTULINA PERSONALIZADA<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Preciosa bolsa para meter los detalles de la boda, bautizo o comuni\u00f3n. Esta bolsita combina los materiales de jute y tela color blanco roto. Decorada con lazo de yute con bot\u00f3n de madera en el [&hellip;]<\/p>\n","protected":false},"featured_media":11844,"template":"","meta":[],"product_brand":[],"product_cat":[45],"product_tag":[207],"class_list":{"0":"post-2139","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-bolsitas","7":"product_tag-boda-tematica-rustica","8":"clearfix","10":"first","11":"instock","12":"sale","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/www.misdetallesdeboda.com\/detalles\/wp-json\/wp\/v2\/product\/2139","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.misdetallesdeboda.com\/detalles\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.misdetallesdeboda.com\/detalles\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.misdetallesdeboda.com\/detalles\/wp-json\/wp\/v2\/media\/11844"}],"wp:attachment":[{"href":"https:\/\/www.misdetallesdeboda.com\/detalles\/wp-json\/wp\/v2\/media?parent=2139"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.misdetallesdeboda.com\/detalles\/wp-json\/wp\/v2\/product_brand?post=2139"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.misdetallesdeboda.com\/detalles\/wp-json\/wp\/v2\/product_cat?post=2139"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.misdetallesdeboda.com\/detalles\/wp-json\/wp\/v2\/product_tag?post=2139"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}